{"id":26204,"date":"2021-10-22T14:21:16","date_gmt":"2021-10-22T12:21:16","guid":{"rendered":"https:\/\/www.lovatoelectric.com\/news-events\/company-news\/"},"modified":"2022-04-28T12:36:12","modified_gmt":"2022-04-28T10:36:12","slug":"%d0%bd%d0%be%d0%b2%d0%be%d1%81%d1%82%d0%b8-%d0%ba%d0%be%d0%bc%d0%bf%d0%b0%d0%bd%d0%b8%d0%b8","status":"publish","type":"page","link":"https:\/\/www.lovatoelectric.com\/gl_ru\/%d0%bd%d0%be%d0%b2%d0%be%d1%81%d1%82%d0%b8-%d0%b8-%d1%81%d0%be%d0%b1%d1%8b%d1%82%d0%b8%d1%8f\/%d0%bd%d0%be%d0%b2%d0%be%d1%81%d1%82%d0%b8-%d0%ba%d0%be%d0%bc%d0%bf%d0%b0%d0%bd%d0%b8%d0%b8\/","title":{"rendered":"\u041d\u043e\u0432\u043e\u0441\u0442\u0438 \u043a\u043e\u043c\u043f\u0430\u043d\u0438\u0438"},"content":{"rendered":"<div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-1 fusion-flex-container nonhundred-percent-fullwidth non-hundred-percent-height-scrolling\" style=\"--awb-border-radius-top-left:0px;--awb-border-radius-top-right:0px;--awb-border-radius-bottom-right:0px;--awb-border-radius-bottom-left:0px;--awb-flex-wrap:wrap;\" ><div class=\"fusion-builder-row fusion-row fusion-flex-align-items-flex-start fusion-flex-content-wrap\" style=\"max-width:1320.8px;margin-left: calc(-4% \/ 2 );margin-right: calc(-4% \/ 2 );\"><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-0 fusion_builder_column_1_1 1_1 fusion-flex-column\" style=\"--awb-bg-size:cover;--awb-width-large:100%;--awb-margin-top-large:0px;--awb-spacing-right-large:1.92%;--awb-margin-bottom-large:0px;--awb-spacing-left-large:1.92%;--awb-width-medium:100%;--awb-spacing-right-medium:1.92%;--awb-spacing-left-medium:1.92%;--awb-width-small:100%;--awb-spacing-right-small:1.92%;--awb-spacing-left-small:1.92%;\"><div class=\"fusion-column-wrapper fusion-flex-justify-content-flex-start fusion-content-layout-column\"><div class=\"fusion-title title fusion-title-1 fusion-sep-none fusion-title-text fusion-title-size-two\"><h2 class=\"fusion-title-heading title-heading-left fusion-responsive-typography-calculated\" style=\"margin:0;--fontSize:44;line-height:1.26;\">\u041d\u043e\u0432\u043e\u0441\u0442\u0438 \u043a\u043e\u043c\u043f\u0430\u043d\u0438\u0438<\/h2><\/div><div class=\"fusion-blog-shortcode fusion-blog-shortcode-1 fusion-blog-archive fusion-blog-layout-grid-wrapper fusion-blog-infinite\"><style type=\"text\/css\">.fusion-blog-shortcode-1 .fusion-blog-layout-grid .fusion-post-grid{padding:20px;}.fusion-blog-shortcode-1 .fusion-posts-container{margin-left: -20px !important; margin-right:-20px !important;}<\/style><div class=\"fusion-posts-container fusion-posts-container-infinite fusion-posts-container-load-more fusion-no-meta-info fusion-blog-rollover fusion-blog-layout-grid fusion-blog-layout-grid-3 isotope fusion-blog-equal-heights\" data-pages=\"2\" data-grid-col-space=\"40\" style=\"margin: -20px -20px 0;min-height:500px;\"><article id=\"blog-1-post-204720\" class=\"fusion-post-grid post-204720 post type-post status-publish format-standard has-post-thumbnail hentry category-comunicati-stampa-gl_ru category-company-news-gl_ru category-latest-news-gl_ru\">\n<div class=\"fusion-post-wrapper\" style=\"background-color:rgba(255,255,255,0);border:none;\">\n\n\t\t\t<div class=\"fusion-flexslider flexslider fusion-flexslider-loading fusion-post-slideshow\" style=\"border-color:rgba(40,45,51,0);\">\n\t\t<ul class=\"slides\">\n\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<li><div  class=\"fusion-image-wrapper\" aria-haspopup=\"true\">\n\t\t\t\t<img decoding=\"async\" width=\"600\" height=\"400\" src=\"https:\/\/www.lovatoelectric.com\/wp-content\/uploads\/2026\/04\/Brasile_3.jpg\" class=\"attachment-full size-full lazyload wp-post-image\" alt=\"\" srcset=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%27http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%27%20width%3D%27600%27%20height%3D%27400%27%20viewBox%3D%270%200%20600%20400%27%3E%3Crect%20width%3D%27600%27%20height%3D%27400%27%20fill-opacity%3D%220%22%2F%3E%3C%2Fsvg%3E\" data-orig-src=\"https:\/\/www.lovatoelectric.com\/wp-content\/uploads\/2026\/04\/Brasile_3.jpg\" data-srcset=\"https:\/\/www.lovatoelectric.com\/wp-content\/uploads\/2026\/04\/Brasile_3-200x133.jpg 200w, https:\/\/www.lovatoelectric.com\/wp-content\/uploads\/2026\/04\/Brasile_3-400x267.jpg 400w, https:\/\/www.lovatoelectric.com\/wp-content\/uploads\/2026\/04\/Brasile_3.jpg 600w\" data-sizes=\"auto\" \/><div class=\"fusion-rollover\">\n\t<div class=\"fusion-rollover-content\">\n\n\t\t\t\t\n\t\t\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\n\t\t\t\t\t\t<a class=\"fusion-link-wrapper\" href=\"https:\/\/www.lovatoelectric.com\/gl_ru\/lovato-electric-opens-its-fifteenth-subsidiary-in-brazil\/\" aria-label=\"LOVATO Electric opens its fifteenth subsidiary in Brazil\"><\/a>\n\t<\/div>\n<\/div>\n<\/div>\n<\/li>\n\t\t\t\n\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/ul>\n\t<\/div>\n\t<div class=\"fusion-post-content-wrapper\" style=\"padding:30px 0px 10px 0px;\"><div class=\"fusion-post-content post-content\"><h2 class=\"blog-shortcode-post-title entry-title\"><a href=\"https:\/\/www.lovatoelectric.com\/gl_ru\/lovato-electric-opens-its-fifteenth-subsidiary-in-brazil\/\">LOVATO Electric opens its fifteenth subsidiary in Brazil<\/a><\/h2><\/div><\/div><div class=\"fusion-clearfix\"><\/div><\/div>\n<\/article>\n<article id=\"blog-1-post-135547\" class=\"fusion-post-grid post-135547 post type-post status-publish format-standard has-post-thumbnail hentry category-company-news-gl_ru category-latest-news-gl_ru\">\n<div class=\"fusion-post-wrapper\" style=\"background-color:rgba(255,255,255,0);border:none;\">\n\n\t\t\t<div class=\"fusion-flexslider flexslider fusion-flexslider-loading fusion-post-slideshow\" style=\"border-color:rgba(40,45,51,0);\">\n\t\t<ul class=\"slides\">\n\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<li><div  class=\"fusion-image-wrapper\" aria-haspopup=\"true\">\n\t\t\t\t<img decoding=\"async\" width=\"600\" height=\"400\" src=\"https:\/\/www.lovatoelectric.com\/wp-content\/uploads\/2024\/10\/thumb.jpg\" class=\"attachment-full size-full lazyload wp-post-image\" alt=\"\" srcset=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%27http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%27%20width%3D%27600%27%20height%3D%27400%27%20viewBox%3D%270%200%20600%20400%27%3E%3Crect%20width%3D%27600%27%20height%3D%27400%27%20fill-opacity%3D%220%22%2F%3E%3C%2Fsvg%3E\" data-orig-src=\"https:\/\/www.lovatoelectric.com\/wp-content\/uploads\/2024\/10\/thumb.jpg\" data-srcset=\"https:\/\/www.lovatoelectric.com\/wp-content\/uploads\/2024\/10\/thumb-200x133.jpg 200w, https:\/\/www.lovatoelectric.com\/wp-content\/uploads\/2024\/10\/thumb-400x267.jpg 400w, https:\/\/www.lovatoelectric.com\/wp-content\/uploads\/2024\/10\/thumb.jpg 600w\" data-sizes=\"auto\" \/><div class=\"fusion-rollover\">\n\t<div class=\"fusion-rollover-content\">\n\n\t\t\t\t\n\t\t\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\n\t\t\t\t\t\t<a class=\"fusion-link-wrapper\" href=\"https:\/\/www.lovatoelectric.com\/gl_ru\/lovato-electrics-supplier-day\/\" aria-label=\"LOVATO Electric&#8217;s Supplier Day\"><\/a>\n\t<\/div>\n<\/div>\n<\/div>\n<\/li>\n\t\t\t\n\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/ul>\n\t<\/div>\n\t<div class=\"fusion-post-content-wrapper\" style=\"padding:30px 0px 10px 0px;\"><div class=\"fusion-post-content post-content\"><h2 class=\"blog-shortcode-post-title entry-title\"><a href=\"https:\/\/www.lovatoelectric.com\/gl_ru\/lovato-electrics-supplier-day\/\">LOVATO Electric&#8217;s Supplier Day<\/a><\/h2><\/div><\/div><div class=\"fusion-clearfix\"><\/div><\/div>\n<\/article>\n<article id=\"blog-1-post-118438\" class=\"fusion-post-grid post-118438 post type-post status-publish format-standard has-post-thumbnail hentry category-company-news-gl_ru category-latest-news-gl_ru\">\n<div class=\"fusion-post-wrapper\" style=\"background-color:rgba(255,255,255,0);border:none;\">\n\n\t\t\t<div class=\"fusion-flexslider flexslider fusion-flexslider-loading fusion-post-slideshow\" style=\"border-color:rgba(40,45,51,0);\">\n\t\t<ul class=\"slides\">\n\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<li><div  class=\"fusion-image-wrapper\" aria-haspopup=\"true\">\n\t\t\t\t<img decoding=\"async\" width=\"600\" height=\"400\" src=\"https:\/\/www.lovatoelectric.com\/wp-content\/uploads\/2024\/04\/img-catalogue.jpg\" class=\"attachment-full size-full lazyload wp-post-image\" alt=\"\" srcset=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%27http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%27%20width%3D%27600%27%20height%3D%27400%27%20viewBox%3D%270%200%20600%20400%27%3E%3Crect%20width%3D%27600%27%20height%3D%27400%27%20fill-opacity%3D%220%22%2F%3E%3C%2Fsvg%3E\" data-orig-src=\"https:\/\/www.lovatoelectric.com\/wp-content\/uploads\/2024\/04\/img-catalogue.jpg\" data-srcset=\"https:\/\/www.lovatoelectric.com\/wp-content\/uploads\/2024\/04\/img-catalogue-200x133.jpg 200w, https:\/\/www.lovatoelectric.com\/wp-content\/uploads\/2024\/04\/img-catalogue-400x267.jpg 400w, https:\/\/www.lovatoelectric.com\/wp-content\/uploads\/2024\/04\/img-catalogue.jpg 600w\" data-sizes=\"auto\" \/><div class=\"fusion-rollover\">\n\t<div class=\"fusion-rollover-content\">\n\n\t\t\t\t\n\t\t\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\n\t\t\t\t\t\t<a class=\"fusion-link-wrapper\" href=\"https:\/\/www.lovatoelectric.com\/gl_ru\/lovato-electrics-new-general-catalogue-2024-2025-is-now-available\/\" aria-label=\"LOVATO Electric&#8217;s new General Catalogue 2024-2025 is now available\"><\/a>\n\t<\/div>\n<\/div>\n<\/div>\n<\/li>\n\t\t\t\n\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/ul>\n\t<\/div>\n\t<div class=\"fusion-post-content-wrapper\" style=\"padding:30px 0px 10px 0px;\"><div class=\"fusion-post-content post-content\"><h2 class=\"blog-shortcode-post-title entry-title\"><a href=\"https:\/\/www.lovatoelectric.com\/gl_ru\/lovato-electrics-new-general-catalogue-2024-2025-is-now-available\/\">LOVATO Electric&#8217;s new General Catalogue 2024-2025 is now available<\/a><\/h2><\/div><\/div><div class=\"fusion-clearfix\"><\/div><\/div>\n<\/article>\n<article id=\"blog-1-post-100865\" class=\"fusion-post-grid post-100865 post type-post status-publish format-standard has-post-thumbnail hentry category-company-news-gl_ru category-latest-news-gl_ru\">\n<div class=\"fusion-post-wrapper\" style=\"background-color:rgba(255,255,255,0);border:none;\">\n\n\t\t\t<div class=\"fusion-flexslider flexslider fusion-flexslider-loading fusion-post-slideshow\" style=\"border-color:rgba(40,45,51,0);\">\n\t\t<ul class=\"slides\">\n\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<li><div  class=\"fusion-image-wrapper\" aria-haspopup=\"true\">\n\t\t\t\t<img decoding=\"async\" width=\"600\" height=\"400\" src=\"https:\/\/www.lovatoelectric.com\/wp-content\/uploads\/2023\/11\/Anechoic-chamber.jpg\" class=\"attachment-full size-full lazyload wp-post-image\" alt=\"\" srcset=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%27http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%27%20width%3D%27600%27%20height%3D%27400%27%20viewBox%3D%270%200%20600%20400%27%3E%3Crect%20width%3D%27600%27%20height%3D%27400%27%20fill-opacity%3D%220%22%2F%3E%3C%2Fsvg%3E\" data-orig-src=\"https:\/\/www.lovatoelectric.com\/wp-content\/uploads\/2023\/11\/Anechoic-chamber.jpg\" data-srcset=\"https:\/\/www.lovatoelectric.com\/wp-content\/uploads\/2023\/11\/Anechoic-chamber-200x133.jpg 200w, https:\/\/www.lovatoelectric.com\/wp-content\/uploads\/2023\/11\/Anechoic-chamber-400x267.jpg 400w, https:\/\/www.lovatoelectric.com\/wp-content\/uploads\/2023\/11\/Anechoic-chamber.jpg 600w\" data-sizes=\"auto\" \/><div class=\"fusion-rollover\">\n\t<div class=\"fusion-rollover-content\">\n\n\t\t\t\t\n\t\t\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\n\t\t\t\t\t\t<a class=\"fusion-link-wrapper\" href=\"https:\/\/www.lovatoelectric.com\/gl_ru\/%d0%bd%d0%be%d0%b2%d0%b0%d1%8f-%d0%b1%d0%b5%d0%b7%d1%8d%d1%85%d0%be%d0%b2%d0%b0%d1%8f-%d0%ba%d0%b0%d0%bc%d0%b5%d1%80%d0%b0-%d0%b2-%d0%bd%d0%b0%d1%83%d1%87%d0%bd%d0%be-%d0%b8%d1%81%d1%81%d0%bb%d0%b5\/\" aria-label=\"\u041d\u043e\u0432\u0430\u044f \u0431\u0435\u0437\u044d\u0445\u043e\u0432\u0430\u044f \u043a\u0430\u043c\u0435\u0440\u0430 \u0432 \u043d\u0430\u0443\u0447\u043d\u043e-\u0438\u0441\u0441\u043b\u0435\u0434\u043e\u0432\u0430\u0442\u0435\u043b\u044c\u0441\u043a\u043e\u0439 \u043b\u0430\u0431\u043e\u0440\u0430\u0442\u043e\u0440\u0438\u0438\"><\/a>\n\t<\/div>\n<\/div>\n<\/div>\n<\/li>\n\t\t\t\n\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/ul>\n\t<\/div>\n\t<div class=\"fusion-post-content-wrapper\" style=\"padding:30px 0px 10px 0px;\"><div class=\"fusion-post-content post-content\"><h2 class=\"blog-shortcode-post-title entry-title\"><a href=\"https:\/\/www.lovatoelectric.com\/gl_ru\/%d0%bd%d0%be%d0%b2%d0%b0%d1%8f-%d0%b1%d0%b5%d0%b7%d1%8d%d1%85%d0%be%d0%b2%d0%b0%d1%8f-%d0%ba%d0%b0%d0%bc%d0%b5%d1%80%d0%b0-%d0%b2-%d0%bd%d0%b0%d1%83%d1%87%d0%bd%d0%be-%d0%b8%d1%81%d1%81%d0%bb%d0%b5\/\">\u041d\u043e\u0432\u0430\u044f \u0431\u0435\u0437\u044d\u0445\u043e\u0432\u0430\u044f \u043a\u0430\u043c\u0435\u0440\u0430 \u0432 \u043d\u0430\u0443\u0447\u043d\u043e-\u0438\u0441\u0441\u043b\u0435\u0434\u043e\u0432\u0430\u0442\u0435\u043b\u044c\u0441\u043a\u043e\u0439 \u043b\u0430\u0431\u043e\u0440\u0430\u0442\u043e\u0440\u0438\u0438<\/a><\/h2><\/div><\/div><div class=\"fusion-clearfix\"><\/div><\/div>\n<\/article>\n<article id=\"blog-1-post-91160\" class=\"fusion-post-grid post-91160 post type-post status-publish format-standard has-post-thumbnail hentry category-latest-news-gl_ru\">\n<div class=\"fusion-post-wrapper\" style=\"background-color:rgba(255,255,255,0);border:none;\">\n\n\t\t\t<div class=\"fusion-flexslider flexslider fusion-flexslider-loading fusion-post-slideshow\" style=\"border-color:rgba(40,45,51,0);\">\n\t\t<ul class=\"slides\">\n\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<li><div  class=\"fusion-image-wrapper\" aria-haspopup=\"true\">\n\t\t\t\t<img decoding=\"async\" width=\"600\" height=\"400\" src=\"https:\/\/www.lovatoelectric.com\/wp-content\/uploads\/2023\/06\/img-1.jpg\" class=\"attachment-full size-full lazyload wp-post-image\" alt=\"\" srcset=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%27http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%27%20width%3D%27600%27%20height%3D%27400%27%20viewBox%3D%270%200%20600%20400%27%3E%3Crect%20width%3D%27600%27%20height%3D%27400%27%20fill-opacity%3D%220%22%2F%3E%3C%2Fsvg%3E\" data-orig-src=\"https:\/\/www.lovatoelectric.com\/wp-content\/uploads\/2023\/06\/img-1.jpg\" data-srcset=\"https:\/\/www.lovatoelectric.com\/wp-content\/uploads\/2023\/06\/img-1-200x133.jpg 200w, https:\/\/www.lovatoelectric.com\/wp-content\/uploads\/2023\/06\/img-1-400x267.jpg 400w, https:\/\/www.lovatoelectric.com\/wp-content\/uploads\/2023\/06\/img-1.jpg 600w\" data-sizes=\"auto\" \/><div class=\"fusion-rollover\">\n\t<div class=\"fusion-rollover-content\">\n\n\t\t\t\t\n\t\t\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\n\t\t\t\t\t\t<a class=\"fusion-link-wrapper\" href=\"https:\/\/www.lovatoelectric.com\/gl_ru\/%d0%bd%d0%bd%d0%be%d0%b2%d1%8b%d0%b9-%d1%81%d0%b0%d0%b9%d1%82-%d0%b0%d0%ba%d0%b0%d0%b4%d0%b5%d0%bc%d0%b8%d0%b8-lovato\/\" aria-label=\"\u041d\u043d\u043e\u0432\u044b\u0439 \u0441\u0430\u0439\u0442 \u0430\u043a\u0430\u0434\u0435\u043c\u0438\u0438 LOVATO\"><\/a>\n\t<\/div>\n<\/div>\n<\/div>\n<\/li>\n\t\t\t\n\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/ul>\n\t<\/div>\n\t<div class=\"fusion-post-content-wrapper\" style=\"padding:30px 0px 10px 0px;\"><div class=\"fusion-post-content post-content\"><h2 class=\"blog-shortcode-post-title entry-title\"><a href=\"https:\/\/www.lovatoelectric.com\/gl_ru\/%d0%bd%d0%bd%d0%be%d0%b2%d1%8b%d0%b9-%d1%81%d0%b0%d0%b9%d1%82-%d0%b0%d0%ba%d0%b0%d0%b4%d0%b5%d0%bc%d0%b8%d0%b8-lovato\/\">\u041d\u043d\u043e\u0432\u044b\u0439 \u0441\u0430\u0439\u0442 \u0430\u043a\u0430\u0434\u0435\u043c\u0438\u0438 LOVATO<\/a><\/h2><\/div><\/div><div class=\"fusion-clearfix\"><\/div><\/div>\n<\/article>\n<article id=\"blog-1-post-88597\" class=\"fusion-post-grid post-88597 post type-post status-publish format-standard has-post-thumbnail hentry category-latest-news-gl_ru\">\n<div class=\"fusion-post-wrapper\" style=\"background-color:rgba(255,255,255,0);border:none;\">\n\n\t\t\t<div class=\"fusion-flexslider flexslider fusion-flexslider-loading fusion-post-slideshow\" style=\"border-color:rgba(40,45,51,0);\">\n\t\t<ul class=\"slides\">\n\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<li><div  class=\"fusion-image-wrapper\" aria-haspopup=\"true\">\n\t\t\t\t<img decoding=\"async\" width=\"600\" height=\"400\" src=\"https:\/\/www.lovatoelectric.com\/wp-content\/uploads\/2023\/04\/product-declaration.jpg\" class=\"attachment-full size-full lazyload wp-post-image\" alt=\"\" srcset=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%27http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%27%20width%3D%27600%27%20height%3D%27400%27%20viewBox%3D%270%200%20600%20400%27%3E%3Crect%20width%3D%27600%27%20height%3D%27400%27%20fill-opacity%3D%220%22%2F%3E%3C%2Fsvg%3E\" data-orig-src=\"https:\/\/www.lovatoelectric.com\/wp-content\/uploads\/2023\/04\/product-declaration.jpg\" data-srcset=\"https:\/\/www.lovatoelectric.com\/wp-content\/uploads\/2023\/04\/product-declaration-200x133.jpg 200w, https:\/\/www.lovatoelectric.com\/wp-content\/uploads\/2023\/04\/product-declaration-400x267.jpg 400w, https:\/\/www.lovatoelectric.com\/wp-content\/uploads\/2023\/04\/product-declaration.jpg 600w\" data-sizes=\"auto\" \/><div class=\"fusion-rollover\">\n\t<div class=\"fusion-rollover-content\">\n\n\t\t\t\t\n\t\t\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\n\t\t\t\t\t\t<a class=\"fusion-link-wrapper\" href=\"https:\/\/www.lovatoelectric.com\/gl_ru\/%d0%b2%d0%b0%d0%bc-%d0%bd%d1%83%d0%b6%d0%bd%d0%b0-%d0%b4%d0%b5%d0%ba%d0%bb%d0%b0%d1%80%d0%b0%d1%86%d0%b8%d1%8f-%d0%bd%d0%b0-%d0%bf%d1%80%d0%be%d0%b4%d1%83%d0%ba%d1%86%d0%b8%d1%8e\/\" aria-label=\"\u0412\u0430\u043c \u043d\u0443\u0436\u043d\u0430 \u0434\u0435\u043a\u043b\u0430\u0440\u0430\u0446\u0438\u044f \u043d\u0430 \u043f\u0440\u043e\u0434\u0443\u043a\u0446\u0438\u044e?\"><\/a>\n\t<\/div>\n<\/div>\n<\/div>\n<\/li>\n\t\t\t\n\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/ul>\n\t<\/div>\n\t<div class=\"fusion-post-content-wrapper\" style=\"padding:30px 0px 10px 0px;\"><div class=\"fusion-post-content post-content\"><h2 class=\"blog-shortcode-post-title entry-title\"><a href=\"https:\/\/www.lovatoelectric.com\/gl_ru\/%d0%b2%d0%b0%d0%bc-%d0%bd%d1%83%d0%b6%d0%bd%d0%b0-%d0%b4%d0%b5%d0%ba%d0%bb%d0%b0%d1%80%d0%b0%d1%86%d0%b8%d1%8f-%d0%bd%d0%b0-%d0%bf%d1%80%d0%be%d0%b4%d1%83%d0%ba%d1%86%d0%b8%d1%8e\/\">\u0412\u0430\u043c \u043d\u0443\u0436\u043d\u0430 \u0434\u0435\u043a\u043b\u0430\u0440\u0430\u0446\u0438\u044f \u043d\u0430 \u043f\u0440\u043e\u0434\u0443\u043a\u0446\u0438\u044e?<\/a><\/h2><\/div><\/div><div class=\"fusion-clearfix\"><\/div><\/div>\n<\/article>\n<article id=\"blog-1-post-86275\" class=\"fusion-post-grid post-86275 post type-post status-publish format-standard has-post-thumbnail hentry category-company-news-gl_ru category-latest-news-gl_ru\">\n<div class=\"fusion-post-wrapper\" style=\"background-color:rgba(255,255,255,0);border:none;\">\n\n\t\t\t<div class=\"fusion-flexslider flexslider fusion-flexslider-loading fusion-post-slideshow\" style=\"border-color:rgba(40,45,51,0);\">\n\t\t<ul class=\"slides\">\n\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<li><div  class=\"fusion-image-wrapper\" aria-haspopup=\"true\">\n\t\t\t\t<img decoding=\"async\" width=\"600\" height=\"400\" src=\"https:\/\/www.lovatoelectric.com\/wp-content\/uploads\/2023\/02\/NFC-website-1-1.png\" class=\"attachment-full size-full lazyload wp-post-image\" alt=\"\" srcset=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%27http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%27%20width%3D%27600%27%20height%3D%27400%27%20viewBox%3D%270%200%20600%20400%27%3E%3Crect%20width%3D%27600%27%20height%3D%27400%27%20fill-opacity%3D%220%22%2F%3E%3C%2Fsvg%3E\" data-orig-src=\"https:\/\/www.lovatoelectric.com\/wp-content\/uploads\/2023\/02\/NFC-website-1-1.png\" data-srcset=\"https:\/\/www.lovatoelectric.com\/wp-content\/uploads\/2023\/02\/NFC-website-1-1-200x133.png 200w, https:\/\/www.lovatoelectric.com\/wp-content\/uploads\/2023\/02\/NFC-website-1-1-400x267.png 400w, https:\/\/www.lovatoelectric.com\/wp-content\/uploads\/2023\/02\/NFC-website-1-1.png 600w\" data-sizes=\"auto\" \/><div class=\"fusion-rollover\">\n\t<div class=\"fusion-rollover-content\">\n\n\t\t\t\t\n\t\t\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\n\t\t\t\t\t\t<a class=\"fusion-link-wrapper\" href=\"https:\/\/www.lovatoelectric.com\/gl_ru\/lovato-nfc-app-new-video\/\" aria-label=\"\u041f\u0440\u0438\u043b\u043e\u0436\u0435\u043d\u0438\u0435 LOVATO NFC | \u043d\u043e\u0432\u043e\u0435 \u0432\u0438\u0434\u0435\u043e\"><\/a>\n\t<\/div>\n<\/div>\n<\/div>\n<\/li>\n\t\t\t\n\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/ul>\n\t<\/div>\n\t<div class=\"fusion-post-content-wrapper\" style=\"padding:30px 0px 10px 0px;\"><div class=\"fusion-post-content post-content\"><h2 class=\"blog-shortcode-post-title entry-title\"><a href=\"https:\/\/www.lovatoelectric.com\/gl_ru\/lovato-nfc-app-new-video\/\">\u041f\u0440\u0438\u043b\u043e\u0436\u0435\u043d\u0438\u0435 LOVATO NFC | \u043d\u043e\u0432\u043e\u0435 \u0432\u0438\u0434\u0435\u043e<\/a><\/h2><\/div><\/div><div class=\"fusion-clearfix\"><\/div><\/div>\n<\/article>\n<article id=\"blog-1-post-70589\" class=\"fusion-post-grid post-70589 post type-post status-publish format-standard has-post-thumbnail hentry category-company-news-gl_ru category-latest-news-gl_ru\">\n<div class=\"fusion-post-wrapper\" style=\"background-color:rgba(255,255,255,0);border:none;\">\n\n\t\t\t<div class=\"fusion-flexslider flexslider fusion-flexslider-loading fusion-post-slideshow\" style=\"border-color:rgba(40,45,51,0);\">\n\t\t<ul class=\"slides\">\n\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<li><div  class=\"fusion-image-wrapper\" aria-haspopup=\"true\">\n\t\t\t\t<img decoding=\"async\" width=\"600\" height=\"400\" src=\"https:\/\/www.lovatoelectric.com\/wp-content\/uploads\/2022\/12\/Video-preview.jpg\" class=\"attachment-full size-full lazyload wp-post-image\" alt=\"\" srcset=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%27http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%27%20width%3D%27600%27%20height%3D%27400%27%20viewBox%3D%270%200%20600%20400%27%3E%3Crect%20width%3D%27600%27%20height%3D%27400%27%20fill-opacity%3D%220%22%2F%3E%3C%2Fsvg%3E\" data-orig-src=\"https:\/\/www.lovatoelectric.com\/wp-content\/uploads\/2022\/12\/Video-preview.jpg\" data-srcset=\"https:\/\/www.lovatoelectric.com\/wp-content\/uploads\/2022\/12\/Video-preview-200x133.jpg 200w, https:\/\/www.lovatoelectric.com\/wp-content\/uploads\/2022\/12\/Video-preview-400x267.jpg 400w, https:\/\/www.lovatoelectric.com\/wp-content\/uploads\/2022\/12\/Video-preview.jpg 600w\" data-sizes=\"auto\" \/><div class=\"fusion-rollover\">\n\t<div class=\"fusion-rollover-content\">\n\n\t\t\t\t\n\t\t\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\n\t\t\t\t\t\t<a class=\"fusion-link-wrapper\" href=\"https:\/\/www.lovatoelectric.com\/gl_ru\/%d1%81%d0%bb%d0%b5%d0%b4%d1%83%d0%b9-%d0%b7%d0%b0-%d0%b0%d0%bf%d0%b5%d0%bb%d1%8c%d1%81%d0%b8%d0%bd%d0%be%d0%bc-%d0%bf%d0%b5%d1%80%d0%b2%d1%8b%d0%b9-%d0%b4%d0%b5%d0%bd%d1%8c-%d1%81%d0%bb\/\" aria-label=\"\u0421\u043b\u0435\u0434\u0443\u0439 \u0437\u0430 \u0430\u043f\u0435\u043b\u044c\u0441\u0438\u043d\u043e\u043c \u2014 \u043f\u0435\u0440\u0432\u044b\u0439 \u0434\u0435\u043d\u044c \u0441\u043b\u0435\u0434\u0443\u044e\u0449\u0438\u0445 100 \u043b\u0435\u0442\"><\/a>\n\t<\/div>\n<\/div>\n<\/div>\n<\/li>\n\t\t\t\n\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/ul>\n\t<\/div>\n\t<div class=\"fusion-post-content-wrapper\" style=\"padding:30px 0px 10px 0px;\"><div class=\"fusion-post-content post-content\"><h2 class=\"blog-shortcode-post-title entry-title\"><a href=\"https:\/\/www.lovatoelectric.com\/gl_ru\/%d1%81%d0%bb%d0%b5%d0%b4%d1%83%d0%b9-%d0%b7%d0%b0-%d0%b0%d0%bf%d0%b5%d0%bb%d1%8c%d1%81%d0%b8%d0%bd%d0%be%d0%bc-%d0%bf%d0%b5%d1%80%d0%b2%d1%8b%d0%b9-%d0%b4%d0%b5%d0%bd%d1%8c-%d1%81%d0%bb\/\">\u0421\u043b\u0435\u0434\u0443\u0439 \u0437\u0430 \u0430\u043f\u0435\u043b\u044c\u0441\u0438\u043d\u043e\u043c \u2014 \u043f\u0435\u0440\u0432\u044b\u0439 \u0434\u0435\u043d\u044c \u0441\u043b\u0435\u0434\u0443\u044e\u0449\u0438\u0445 100 \u043b\u0435\u0442<\/a><\/h2><\/div><\/div><div class=\"fusion-clearfix\"><\/div><\/div>\n<\/article>\n<article id=\"blog-1-post-69261\" class=\"fusion-post-grid post-69261 post type-post status-publish format-standard has-post-thumbnail hentry category-company-news-gl_ru category-latest-news-gl_ru\">\n<div class=\"fusion-post-wrapper\" style=\"background-color:rgba(255,255,255,0);border:none;\">\n\n\t\t\t<div class=\"fusion-flexslider flexslider fusion-flexslider-loading fusion-post-slideshow\" style=\"border-color:rgba(40,45,51,0);\">\n\t\t<ul class=\"slides\">\n\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<li><div  class=\"fusion-image-wrapper\" aria-haspopup=\"true\">\n\t\t\t\t<img decoding=\"async\" width=\"600\" height=\"400\" src=\"https:\/\/www.lovatoelectric.com\/wp-content\/uploads\/2022\/11\/Soft-starter-1.jpg\" class=\"attachment-full size-full lazyload wp-post-image\" alt=\"\" srcset=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%27http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%27%20width%3D%27600%27%20height%3D%27400%27%20viewBox%3D%270%200%20600%20400%27%3E%3Crect%20width%3D%27600%27%20height%3D%27400%27%20fill-opacity%3D%220%22%2F%3E%3C%2Fsvg%3E\" data-orig-src=\"https:\/\/www.lovatoelectric.com\/wp-content\/uploads\/2022\/11\/Soft-starter-1.jpg\" data-srcset=\"https:\/\/www.lovatoelectric.com\/wp-content\/uploads\/2022\/11\/Soft-starter-1-200x133.jpg 200w, https:\/\/www.lovatoelectric.com\/wp-content\/uploads\/2022\/11\/Soft-starter-1-400x267.jpg 400w, https:\/\/www.lovatoelectric.com\/wp-content\/uploads\/2022\/11\/Soft-starter-1.jpg 600w\" data-sizes=\"auto\" \/><div class=\"fusion-rollover\">\n\t<div class=\"fusion-rollover-content\">\n\n\t\t\t\t\n\t\t\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\n\t\t\t\t\t\t<a class=\"fusion-link-wrapper\" href=\"https:\/\/www.lovatoelectric.com\/gl_ru\/%d1%83%d1%81%d1%82%d1%80%d0%be%d0%b9%d1%81%d1%82%d0%b2%d0%be-%d0%bf%d0%bb%d0%b0%d0%b2%d0%bd%d0%be%d0%b3%d0%be-%d0%bf%d1%83%d1%81%d0%ba%d0%b0-%d1%81%d0%b5%d1%80%d0%b8%d0%b8-adxn-%d0%bd%d0%be%d0%b2\/\" aria-label=\"\u0423\u0441\u0442\u0440\u043e\u0439\u0441\u0442\u0432\u043e \u043f\u043b\u0430\u0432\u043d\u043e\u0433\u043e \u043f\u0443\u0441\u043a\u0430 \u0441\u0435\u0440\u0438\u0438 ADXN | \u043d\u043e\u0432\u043e\u0435 \u0432\u0438\u0434\u0435\u043e\"><\/a>\n\t<\/div>\n<\/div>\n<\/div>\n<\/li>\n\t\t\t\n\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/ul>\n\t<\/div>\n\t<div class=\"fusion-post-content-wrapper\" style=\"padding:30px 0px 10px 0px;\"><div class=\"fusion-post-content post-content\"><h2 class=\"blog-shortcode-post-title entry-title\"><a href=\"https:\/\/www.lovatoelectric.com\/gl_ru\/%d1%83%d1%81%d1%82%d1%80%d0%be%d0%b9%d1%81%d1%82%d0%b2%d0%be-%d0%bf%d0%bb%d0%b0%d0%b2%d0%bd%d0%be%d0%b3%d0%be-%d0%bf%d1%83%d1%81%d0%ba%d0%b0-%d1%81%d0%b5%d1%80%d0%b8%d0%b8-adxn-%d0%bd%d0%be%d0%b2\/\">\u0423\u0441\u0442\u0440\u043e\u0439\u0441\u0442\u0432\u043e \u043f\u043b\u0430\u0432\u043d\u043e\u0433\u043e \u043f\u0443\u0441\u043a\u0430 \u0441\u0435\u0440\u0438\u0438 ADXN | \u043d\u043e\u0432\u043e\u0435 \u0432\u0438\u0434\u0435\u043e<\/a><\/h2><\/div><\/div><div class=\"fusion-clearfix\"><\/div><\/div>\n<\/article>\n<article id=\"blog-1-post-62354\" class=\"fusion-post-grid post-62354 post type-post status-publish format-standard has-post-thumbnail hentry category-company-news-gl_ru category-latest-news-gl_ru\">\n<div class=\"fusion-post-wrapper\" style=\"background-color:rgba(255,255,255,0);border:none;\">\n\n\t\t\t<div class=\"fusion-flexslider flexslider fusion-flexslider-loading fusion-post-slideshow\" style=\"border-color:rgba(40,45,51,0);\">\n\t\t<ul class=\"slides\">\n\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<li><div  class=\"fusion-image-wrapper\" aria-haspopup=\"true\">\n\t\t\t\t<img decoding=\"async\" width=\"600\" height=\"400\" src=\"https:\/\/www.lovatoelectric.com\/wp-content\/uploads\/2022\/05\/img-news.jpg\" class=\"attachment-full size-full lazyload wp-post-image\" alt=\"\" srcset=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%27http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%27%20width%3D%27600%27%20height%3D%27400%27%20viewBox%3D%270%200%20600%20400%27%3E%3Crect%20width%3D%27600%27%20height%3D%27400%27%20fill-opacity%3D%220%22%2F%3E%3C%2Fsvg%3E\" data-orig-src=\"https:\/\/www.lovatoelectric.com\/wp-content\/uploads\/2022\/05\/img-news.jpg\" data-srcset=\"https:\/\/www.lovatoelectric.com\/wp-content\/uploads\/2022\/05\/img-news-200x133.jpg 200w, https:\/\/www.lovatoelectric.com\/wp-content\/uploads\/2022\/05\/img-news-400x267.jpg 400w, https:\/\/www.lovatoelectric.com\/wp-content\/uploads\/2022\/05\/img-news.jpg 600w\" data-sizes=\"auto\" \/><div class=\"fusion-rollover\">\n\t<div class=\"fusion-rollover-content\">\n\n\t\t\t\t\n\t\t\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\n\t\t\t\t\t\t<a class=\"fusion-link-wrapper\" href=\"https:\/\/www.lovatoelectric.com\/gl_ru\/easy-branch-%d0%bf%d1%80%d0%be%d1%81%d1%82%d0%b0%d1%8f-%d0%bc%d0%bd%d0%be%d0%b3%d0%be%d0%ba%d0%b0%d0%bd%d0%b0%d0%bb%d1%8c%d0%bd%d0%b0%d1%8f-%d0%b8%d0%b7%d0%bc%d0%b5%d1%80%d0%b8%d1%82%d0%b5%d0%bb%d1%8c\/\" aria-label=\"Easy branch \u043f\u0440\u043e\u0441\u0442\u0430\u044f \u043c\u043d\u043e\u0433\u043e\u043a\u0430\u043d\u0430\u043b\u044c\u043d\u0430\u044f \u0438\u0437\u043c\u0435\u0440\u0438\u0442\u0435\u043b\u044c\u043d\u0430\u044f \u0441\u0438\u0441\u0442\u0435\u043c\u0430 | \u043d\u043e\u0432\u043e\u0435 \u0432\u0438\u0434\u0435\u043e\"><\/a>\n\t<\/div>\n<\/div>\n<\/div>\n<\/li>\n\t\t\t\n\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/ul>\n\t<\/div>\n\t<div class=\"fusion-post-content-wrapper\" style=\"padding:30px 0px 10px 0px;\"><div class=\"fusion-post-content post-content\"><h2 class=\"blog-shortcode-post-title entry-title\"><a href=\"https:\/\/www.lovatoelectric.com\/gl_ru\/easy-branch-%d0%bf%d1%80%d0%be%d1%81%d1%82%d0%b0%d1%8f-%d0%bc%d0%bd%d0%be%d0%b3%d0%be%d0%ba%d0%b0%d0%bd%d0%b0%d0%bb%d1%8c%d0%bd%d0%b0%d1%8f-%d0%b8%d0%b7%d0%bc%d0%b5%d1%80%d0%b8%d1%82%d0%b5%d0%bb%d1%8c\/\">Easy branch \u043f\u0440\u043e\u0441\u0442\u0430\u044f \u043c\u043d\u043e\u0433\u043e\u043a\u0430\u043d\u0430\u043b\u044c\u043d\u0430\u044f \u0438\u0437\u043c\u0435\u0440\u0438\u0442\u0435\u043b\u044c\u043d\u0430\u044f \u0441\u0438\u0441\u0442\u0435\u043c\u0430 | \u043d\u043e\u0432\u043e\u0435 \u0432\u0438\u0434\u0435\u043e<\/a><\/h2><\/div><\/div><div class=\"fusion-clearfix\"><\/div><\/div>\n<\/article>\n<article id=\"blog-1-post-33195\" class=\"fusion-post-grid post-33195 post type-post status-publish format-standard has-post-thumbnail hentry category-company-news-gl_ru category-latest-news-gl_ru tag-lovato-2-gl_ru\">\n<div class=\"fusion-post-wrapper\" style=\"background-color:rgba(255,255,255,0);border:none;\">\n\n\t\t\t<div class=\"fusion-flexslider flexslider fusion-flexslider-loading fusion-post-slideshow\" style=\"border-color:rgba(40,45,51,0);\">\n\t\t<ul class=\"slides\">\n\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<li><div  class=\"fusion-image-wrapper\" aria-haspopup=\"true\">\n\t\t\t\t<img decoding=\"async\" width=\"600\" height=\"400\" src=\"https:\/\/www.lovatoelectric.com\/wp-content\/uploads\/2022\/04\/Power-Analyser-DMG-series.jpg\" class=\"attachment-full size-full lazyload wp-post-image\" alt=\"\" srcset=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%27http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%27%20width%3D%27600%27%20height%3D%27400%27%20viewBox%3D%270%200%20600%20400%27%3E%3Crect%20width%3D%27600%27%20height%3D%27400%27%20fill-opacity%3D%220%22%2F%3E%3C%2Fsvg%3E\" data-orig-src=\"https:\/\/www.lovatoelectric.com\/wp-content\/uploads\/2022\/04\/Power-Analyser-DMG-series.jpg\" data-srcset=\"https:\/\/www.lovatoelectric.com\/wp-content\/uploads\/2022\/04\/Power-Analyser-DMG-series-200x133.jpg 200w, https:\/\/www.lovatoelectric.com\/wp-content\/uploads\/2022\/04\/Power-Analyser-DMG-series-400x267.jpg 400w, https:\/\/www.lovatoelectric.com\/wp-content\/uploads\/2022\/04\/Power-Analyser-DMG-series.jpg 600w\" data-sizes=\"auto\" \/><div class=\"fusion-rollover\">\n\t<div class=\"fusion-rollover-content\">\n\n\t\t\t\t\n\t\t\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\n\t\t\t\t\t\t<a class=\"fusion-link-wrapper\" href=\"https:\/\/www.lovatoelectric.com\/gl_ru\/%d0%b0%d0%bd%d0%b0%d0%bb%d0%b8%d0%b7%d0%b0%d1%82%d0%be%d1%80%d1%8b-%d0%ba%d0%b0%d1%87%d0%b5%d1%81%d1%82%d0%b2%d0%b0-%d1%8d%d0%bd%d0%b5%d1%80%d0%b3%d0%be%d0%bf%d0%be%d1%82%d1%80%d0%b5%d0%b1%d0%bb%d0%b5\/\" aria-label=\"\u0410\u043d\u0430\u043b\u0438\u0437\u0430\u0442\u043e\u0440\u044b \u043a\u0430\u0447\u0435\u0441\u0442\u0432\u0430 \u044d\u043d\u0435\u0440\u0433\u043e\u043f\u043e\u0442\u0440\u0435\u0431\u043b\u0435\u043d\u0438\u044f \u0441\u0435\u0440\u0438\u0438 DMG | \u043d\u043e\u0432\u043e\u0435 \u0432\u0438\u0434\u0435\u043e\"><\/a>\n\t<\/div>\n<\/div>\n<\/div>\n<\/li>\n\t\t\t\n\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/ul>\n\t<\/div>\n\t<div class=\"fusion-post-content-wrapper\" style=\"padding:30px 0px 10px 0px;\"><div class=\"fusion-post-content post-content\"><h2 class=\"blog-shortcode-post-title entry-title\"><a href=\"https:\/\/www.lovatoelectric.com\/gl_ru\/%d0%b0%d0%bd%d0%b0%d0%bb%d0%b8%d0%b7%d0%b0%d1%82%d0%be%d1%80%d1%8b-%d0%ba%d0%b0%d1%87%d0%b5%d1%81%d1%82%d0%b2%d0%b0-%d1%8d%d0%bd%d0%b5%d1%80%d0%b3%d0%be%d0%bf%d0%be%d1%82%d1%80%d0%b5%d0%b1%d0%bb%d0%b5\/\">\u0410\u043d\u0430\u043b\u0438\u0437\u0430\u0442\u043e\u0440\u044b \u043a\u0430\u0447\u0435\u0441\u0442\u0432\u0430 \u044d\u043d\u0435\u0440\u0433\u043e\u043f\u043e\u0442\u0440\u0435\u0431\u043b\u0435\u043d\u0438\u044f \u0441\u0435\u0440\u0438\u0438 DMG | \u043d\u043e\u0432\u043e\u0435 \u0432\u0438\u0434\u0435\u043e<\/a><\/h2><\/div><\/div><div class=\"fusion-clearfix\"><\/div><\/div>\n<\/article>\n<article id=\"blog-1-post-55300\" class=\"fusion-post-grid post-55300 post type-post status-publish format-standard has-post-thumbnail hentry category-company-news-gl_ru category-latest-news-gl_ru\">\n<div class=\"fusion-post-wrapper\" style=\"background-color:rgba(255,255,255,0);border:none;\">\n\n\t\t\t<div class=\"fusion-flexslider flexslider fusion-flexslider-loading fusion-post-slideshow\" style=\"border-color:rgba(40,45,51,0);\">\n\t\t<ul class=\"slides\">\n\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<li><div  class=\"fusion-image-wrapper\" aria-haspopup=\"true\">\n\t\t\t\t<img decoding=\"async\" width=\"600\" height=\"400\" src=\"https:\/\/www.lovatoelectric.com\/wp-content\/uploads\/2022\/09\/MYENERGY.png\" class=\"attachment-full size-full lazyload wp-post-image\" alt=\"\" srcset=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%27http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%27%20width%3D%27600%27%20height%3D%27400%27%20viewBox%3D%270%200%20600%20400%27%3E%3Crect%20width%3D%27600%27%20height%3D%27400%27%20fill-opacity%3D%220%22%2F%3E%3C%2Fsvg%3E\" data-orig-src=\"https:\/\/www.lovatoelectric.com\/wp-content\/uploads\/2022\/09\/MYENERGY.png\" data-srcset=\"https:\/\/www.lovatoelectric.com\/wp-content\/uploads\/2022\/09\/MYENERGY-200x133.png 200w, https:\/\/www.lovatoelectric.com\/wp-content\/uploads\/2022\/09\/MYENERGY-400x267.png 400w, https:\/\/www.lovatoelectric.com\/wp-content\/uploads\/2022\/09\/MYENERGY.png 600w\" data-sizes=\"auto\" \/><div class=\"fusion-rollover\">\n\t<div class=\"fusion-rollover-content\">\n\n\t\t\t\t\n\t\t\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\n\t\t\t\t\t\t<a class=\"fusion-link-wrapper\" href=\"https:\/\/www.lovatoelectric.com\/gl_ru\/my-energy-configurator-%d0%bc%d0%be%d0%b9-%d0%ba%d0%be%d0%bd%d1%84%d0%b8%d0%b3%d1%83%d1%80%d0%b0%d1%82%d0%be%d1%80-%d1%8d%d0%bd%d0%b5%d1%80%d0%b3%d0%b8%d0%b8\/\" aria-label=\"My Energy Configurator &#8211; \u041c\u043e\u0439 \u043a\u043e\u043d\u0444\u0438\u0433\u0443\u0440\u0430\u0442\u043e\u0440 \u044d\u043d\u0435\u0440\u0433\u0438\u0438\"><\/a>\n\t<\/div>\n<\/div>\n<\/div>\n<\/li>\n\t\t\t\n\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/ul>\n\t<\/div>\n\t<div class=\"fusion-post-content-wrapper\" style=\"padding:30px 0px 10px 0px;\"><div class=\"fusion-post-content post-content\"><h2 class=\"blog-shortcode-post-title entry-title\"><a href=\"https:\/\/www.lovatoelectric.com\/gl_ru\/my-energy-configurator-%d0%bc%d0%be%d0%b9-%d0%ba%d0%be%d0%bd%d1%84%d0%b8%d0%b3%d1%83%d1%80%d0%b0%d1%82%d0%be%d1%80-%d1%8d%d0%bd%d0%b5%d1%80%d0%b3%d0%b8%d0%b8\/\">My Energy Configurator &#8211; \u041c\u043e\u0439 \u043a\u043e\u043d\u0444\u0438\u0433\u0443\u0440\u0430\u0442\u043e\u0440 \u044d\u043d\u0435\u0440\u0433\u0438\u0438<\/a><\/h2><\/div><\/div><div class=\"fusion-clearfix\"><\/div><\/div>\n<\/article>\n<article id=\"blog-1-post-33197\" class=\"fusion-post-grid post-33197 post type-post status-publish format-standard has-post-thumbnail hentry category-company-news-gl_ru category-latest-news-gl_ru tag-em-gl_ru tag-lovato-2-gl_ru\">\n<div class=\"fusion-post-wrapper\" style=\"background-color:rgba(255,255,255,0);border:none;\">\n\n\t\t\t<div class=\"fusion-flexslider flexslider fusion-flexslider-loading fusion-post-slideshow\" style=\"border-color:rgba(40,45,51,0);\">\n\t\t<ul class=\"slides\">\n\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<li><div  class=\"fusion-image-wrapper\" aria-haspopup=\"true\">\n\t\t\t\t<img decoding=\"async\" width=\"600\" height=\"400\" src=\"https:\/\/www.lovatoelectric.com\/wp-content\/uploads\/2022\/03\/s_Latest-01.jpg\" class=\"attachment-full size-full lazyload wp-post-image\" alt=\"\" srcset=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%27http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%27%20width%3D%27600%27%20height%3D%27400%27%20viewBox%3D%270%200%20600%20400%27%3E%3Crect%20width%3D%27600%27%20height%3D%27400%27%20fill-opacity%3D%220%22%2F%3E%3C%2Fsvg%3E\" data-orig-src=\"https:\/\/www.lovatoelectric.com\/wp-content\/uploads\/2022\/03\/s_Latest-01.jpg\" data-srcset=\"https:\/\/www.lovatoelectric.com\/wp-content\/uploads\/2022\/03\/s_Latest-01-200x133.jpg 200w, https:\/\/www.lovatoelectric.com\/wp-content\/uploads\/2022\/03\/s_Latest-01-400x267.jpg 400w, https:\/\/www.lovatoelectric.com\/wp-content\/uploads\/2022\/03\/s_Latest-01.jpg 600w\" data-sizes=\"auto\" \/><div class=\"fusion-rollover\">\n\t<div class=\"fusion-rollover-content\">\n\n\t\t\t\t\n\t\t\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\n\t\t\t\t\t\t<a class=\"fusion-link-wrapper\" href=\"https:\/\/www.lovatoelectric.com\/gl_ru\/%d0%ba%d0%bd%d0%be%d0%bf%d0%ba%d0%b8-%d0%b8-%d0%bf%d0%b5%d1%80%d0%b5%d0%ba%d0%bb%d1%8e%d1%87%d0%b0%d1%82%d0%b5%d0%bb%d0%b8-%d1%81%d0%b5%d1%80%d0%b8%d0%b8-platinum-%d0%bd%d0%be%d0%b2%d0%be%d0%b5\/\" aria-label=\"\u041a\u043d\u043e\u043f\u043a\u0438 \u0438 \u043f\u0435\u0440\u0435\u043a\u043b\u044e\u0447\u0430\u0442\u0435\u043b\u0438 \u0441\u0435\u0440\u0438\u0438 Platinum | \u043d\u043e\u0432\u043e\u0435 \u0432\u0438\u0434\u0435\u043e\"><\/a>\n\t<\/div>\n<\/div>\n<\/div>\n<\/li>\n\t\t\t\n\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/ul>\n\t<\/div>\n\t<div class=\"fusion-post-content-wrapper\" style=\"padding:30px 0px 10px 0px;\"><div class=\"fusion-post-content post-content\"><h2 class=\"blog-shortcode-post-title entry-title\"><a href=\"https:\/\/www.lovatoelectric.com\/gl_ru\/%d0%ba%d0%bd%d0%be%d0%bf%d0%ba%d0%b8-%d0%b8-%d0%bf%d0%b5%d1%80%d0%b5%d0%ba%d0%bb%d1%8e%d1%87%d0%b0%d1%82%d0%b5%d0%bb%d0%b8-%d1%81%d0%b5%d1%80%d0%b8%d0%b8-platinum-%d0%bd%d0%be%d0%b2%d0%be%d0%b5\/\">\u041a\u043d\u043e\u043f\u043a\u0438 \u0438 \u043f\u0435\u0440\u0435\u043a\u043b\u044e\u0447\u0430\u0442\u0435\u043b\u0438 \u0441\u0435\u0440\u0438\u0438 Platinum | \u043d\u043e\u0432\u043e\u0435 \u0432\u0438\u0434\u0435\u043e<\/a><\/h2><\/div><\/div><div class=\"fusion-clearfix\"><\/div><\/div>\n<\/article>\n<article id=\"blog-1-post-33199\" class=\"fusion-post-grid post-33199 post type-post status-publish format-standard has-post-thumbnail hentry category-company-news-gl_ru category-latest-news-gl_ru tag-academy-gl_ru\">\n<div class=\"fusion-post-wrapper\" style=\"background-color:rgba(255,255,255,0);border:none;\">\n\n\t\t\t<div class=\"fusion-flexslider flexslider fusion-flexslider-loading fusion-post-slideshow\" style=\"border-color:rgba(40,45,51,0);\">\n\t\t<ul class=\"slides\">\n\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<li><div  class=\"fusion-image-wrapper\" aria-haspopup=\"true\">\n\t\t\t\t<img decoding=\"async\" width=\"1200\" height=\"800\" src=\"https:\/\/www.lovatoelectric.com\/wp-content\/uploads\/2021\/08\/Latest-02.jpg\" class=\"attachment-full size-full lazyload wp-post-image\" alt=\"\" srcset=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%27http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%27%20width%3D%271200%27%20height%3D%27800%27%20viewBox%3D%270%200%201200%20800%27%3E%3Crect%20width%3D%271200%27%20height%3D%27800%27%20fill-opacity%3D%220%22%2F%3E%3C%2Fsvg%3E\" data-orig-src=\"https:\/\/www.lovatoelectric.com\/wp-content\/uploads\/2021\/08\/Latest-02.jpg\" data-srcset=\"https:\/\/www.lovatoelectric.com\/wp-content\/uploads\/2021\/08\/Latest-02-200x133.jpg 200w, https:\/\/www.lovatoelectric.com\/wp-content\/uploads\/2021\/08\/Latest-02-400x267.jpg 400w, https:\/\/www.lovatoelectric.com\/wp-content\/uploads\/2021\/08\/Latest-02-600x400.jpg 600w, https:\/\/www.lovatoelectric.com\/wp-content\/uploads\/2021\/08\/Latest-02-800x533.jpg 800w, https:\/\/www.lovatoelectric.com\/wp-content\/uploads\/2021\/08\/Latest-02.jpg 1200w\" data-sizes=\"auto\" \/><div class=\"fusion-rollover\">\n\t<div class=\"fusion-rollover-content\">\n\n\t\t\t\t\n\t\t\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\n\t\t\t\t\t\t<a class=\"fusion-link-wrapper\" href=\"https:\/\/www.lovatoelectric.com\/gl_ru\/lovato-electric-%d0%bf%d1%80%d0%b5%d0%b4%d1%81%d1%82%d0%b0%d0%b2%d0%bb%d1%8f%d0%b5%d1%82-%d1%81%d0%b2%d0%be%d0%b9-%d0%bd%d0%be%d0%b2%d1%8b%d0%b9-%d0%be%d0%b1%d1%89%d0%b8%d0%b9-%d0%ba%d0%b0%d1%82%d0%b0\/\" aria-label=\"LOVATO Electric \u043f\u0440\u0435\u0434\u0441\u0442\u0430\u0432\u043b\u044f\u0435\u0442 \u0441\u0432\u043e\u0439 \u043d\u043e\u0432\u044b\u0439 \u041e\u0431\u0449\u0438\u0439 \u043a\u0430\u0442\u0430\u043b\u043e\u0433 2021-22 \u0433\u0433\"><\/a>\n\t<\/div>\n<\/div>\n<\/div>\n<\/li>\n\t\t\t\n\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/ul>\n\t<\/div>\n\t<div class=\"fusion-post-content-wrapper\" style=\"padding:30px 0px 10px 0px;\"><div class=\"fusion-post-content post-content\"><h2 class=\"blog-shortcode-post-title entry-title\"><a href=\"https:\/\/www.lovatoelectric.com\/gl_ru\/lovato-electric-%d0%bf%d1%80%d0%b5%d0%b4%d1%81%d1%82%d0%b0%d0%b2%d0%bb%d1%8f%d0%b5%d1%82-%d1%81%d0%b2%d0%be%d0%b9-%d0%bd%d0%be%d0%b2%d1%8b%d0%b9-%d0%be%d0%b1%d1%89%d0%b8%d0%b9-%d0%ba%d0%b0%d1%82%d0%b0\/\">LOVATO Electric \u043f\u0440\u0435\u0434\u0441\u0442\u0430\u0432\u043b\u044f\u0435\u0442 \u0441\u0432\u043e\u0439 \u043d\u043e\u0432\u044b\u0439 \u041e\u0431\u0449\u0438\u0439 \u043a\u0430\u0442\u0430\u043b\u043e\u0433 2021-22 \u0433\u0433<\/a><\/h2><\/div><\/div><div class=\"fusion-clearfix\"><\/div><\/div>\n<\/article>\n<article id=\"blog-1-post-33203\" class=\"fusion-post-grid post-33203 post type-post status-publish format-standard has-post-thumbnail hentry category-company-news-gl_ru category-latest-news-gl_ru\">\n<div class=\"fusion-post-wrapper\" style=\"background-color:rgba(255,255,255,0);border:none;\">\n\n\t\t\t<div class=\"fusion-flexslider flexslider fusion-flexslider-loading fusion-post-slideshow\" style=\"border-color:rgba(40,45,51,0);\">\n\t\t<ul class=\"slides\">\n\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<li><div  class=\"fusion-image-wrapper\" aria-haspopup=\"true\">\n\t\t\t\t<img decoding=\"async\" width=\"400\" height=\"267\" src=\"https:\/\/www.lovatoelectric.com\/wp-content\/uploads\/2021\/12\/iOS_NFC_500s.jpg\" class=\"attachment-full size-full lazyload wp-post-image\" alt=\"\" srcset=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%27http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%27%20width%3D%27400%27%20height%3D%27267%27%20viewBox%3D%270%200%20400%20267%27%3E%3Crect%20width%3D%27400%27%20height%3D%27267%27%20fill-opacity%3D%220%22%2F%3E%3C%2Fsvg%3E\" data-orig-src=\"https:\/\/www.lovatoelectric.com\/wp-content\/uploads\/2021\/12\/iOS_NFC_500s.jpg\" data-srcset=\"https:\/\/www.lovatoelectric.com\/wp-content\/uploads\/2021\/12\/iOS_NFC_500s-200x134.jpg 200w, https:\/\/www.lovatoelectric.com\/wp-content\/uploads\/2021\/12\/iOS_NFC_500s.jpg 400w\" data-sizes=\"auto\" \/><div class=\"fusion-rollover\">\n\t<div class=\"fusion-rollover-content\">\n\n\t\t\t\t\n\t\t\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\n\t\t\t\t\t\t<a class=\"fusion-link-wrapper\" href=\"https:\/\/www.lovatoelectric.com\/gl_ru\/%d0%bf%d1%80%d0%b8%d0%bb%d0%be%d0%b6%d0%b5%d0%bd%d0%b8%d0%b5-lovato-nfc-%d1%82%d0%b5%d0%bf%d0%b5%d1%80%d1%8c-%d0%b4%d0%be%d1%81%d1%82%d1%83%d0%bf%d0%bd%d0%be-%d0%b4%d0%bb%d1%8f-ios-%d0%be%d1%82-apple\/\" aria-label=\"\u041f\u0440\u0438\u043b\u043e\u0436\u0435\u043d\u0438\u0435 LOVATO NFC \u0442\u0435\u043f\u0435\u0440\u044c \u0434\u043e\u0441\u0442\u0443\u043f\u043d\u043e \u0434\u043b\u044f iOS \u043e\u0442 Apple\"><\/a>\n\t<\/div>\n<\/div>\n<\/div>\n<\/li>\n\t\t\t\n\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/ul>\n\t<\/div>\n\t<div class=\"fusion-post-content-wrapper\" style=\"padding:30px 0px 10px 0px;\"><div class=\"fusion-post-content post-content\"><h2 class=\"blog-shortcode-post-title entry-title\"><a href=\"https:\/\/www.lovatoelectric.com\/gl_ru\/%d0%bf%d1%80%d0%b8%d0%bb%d0%be%d0%b6%d0%b5%d0%bd%d0%b8%d0%b5-lovato-nfc-%d1%82%d0%b5%d0%bf%d0%b5%d1%80%d1%8c-%d0%b4%d0%be%d1%81%d1%82%d1%83%d0%bf%d0%bd%d0%be-%d0%b4%d0%bb%d1%8f-ios-%d0%be%d1%82-apple\/\">\u041f\u0440\u0438\u043b\u043e\u0436\u0435\u043d\u0438\u0435 LOVATO NFC \u0442\u0435\u043f\u0435\u0440\u044c \u0434\u043e\u0441\u0442\u0443\u043f\u043d\u043e \u0434\u043b\u044f iOS \u043e\u0442 Apple<\/a><\/h2><\/div><\/div><div class=\"fusion-clearfix\"><\/div><\/div>\n<\/article>\n<article id=\"blog-1-post-33205\" class=\"fusion-post-grid post-33205 post type-post status-publish format-standard has-post-thumbnail hentry category-company-news-gl_ru category-latest-news-gl_ru\">\n<div class=\"fusion-post-wrapper\" style=\"background-color:rgba(255,255,255,0);border:none;\">\n\n\t\t\t<div class=\"fusion-flexslider flexslider fusion-flexslider-loading fusion-post-slideshow\" style=\"border-color:rgba(40,45,51,0);\">\n\t\t<ul class=\"slides\">\n\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<li><div  class=\"fusion-image-wrapper\" aria-haspopup=\"true\">\n\t\t\t\t<img decoding=\"async\" width=\"400\" height=\"267\" src=\"https:\/\/www.lovatoelectric.com\/wp-content\/uploads\/2021\/12\/vl.jpg\" class=\"attachment-full size-full lazyload wp-post-image\" alt=\"\" srcset=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%27http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%27%20width%3D%27400%27%20height%3D%27267%27%20viewBox%3D%270%200%20400%20267%27%3E%3Crect%20width%3D%27400%27%20height%3D%27267%27%20fill-opacity%3D%220%22%2F%3E%3C%2Fsvg%3E\" data-orig-src=\"https:\/\/www.lovatoelectric.com\/wp-content\/uploads\/2021\/12\/vl.jpg\" data-srcset=\"https:\/\/www.lovatoelectric.com\/wp-content\/uploads\/2021\/12\/vl-200x134.jpg 200w, https:\/\/www.lovatoelectric.com\/wp-content\/uploads\/2021\/12\/vl.jpg 400w\" data-sizes=\"auto\" \/><div class=\"fusion-rollover\">\n\t<div class=\"fusion-rollover-content\">\n\n\t\t\t\t\n\t\t\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\n\t\t\t\t\t\t<a class=\"fusion-link-wrapper\" href=\"https:\/\/www.lovatoelectric.com\/gl_ru\/%d0%ba%d0%be%d0%bd%d1%82%d0%b0%d0%ba%d1%82%d0%be%d1%80%d1%8b-%d1%81%d0%b5%d1%80%d0%b8%d0%b8-bf-%d0%bd%d0%be%d0%b2%d0%be%d0%b5-%d0%b2%d0%b8%d0%b4%d0%b5%d0%be\/\" aria-label=\"\u041a\u043e\u043d\u0442\u0430\u043a\u0442\u043e\u0440\u044b \u0441\u0435\u0440\u0438\u0438 BF &#8211; \u041d\u043e\u0432\u043e\u0435 \u0432\u0438\u0434\u0435\u043e\"><\/a>\n\t<\/div>\n<\/div>\n<\/div>\n<\/li>\n\t\t\t\n\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/ul>\n\t<\/div>\n\t<div class=\"fusion-post-content-wrapper\" style=\"padding:30px 0px 10px 0px;\"><div class=\"fusion-post-content post-content\"><h2 class=\"blog-shortcode-post-title entry-title\"><a href=\"https:\/\/www.lovatoelectric.com\/gl_ru\/%d0%ba%d0%be%d0%bd%d1%82%d0%b0%d0%ba%d1%82%d0%be%d1%80%d1%8b-%d1%81%d0%b5%d1%80%d0%b8%d0%b8-bf-%d0%bd%d0%be%d0%b2%d0%be%d0%b5-%d0%b2%d0%b8%d0%b4%d0%b5%d0%be\/\">\u041a\u043e\u043d\u0442\u0430\u043a\u0442\u043e\u0440\u044b \u0441\u0435\u0440\u0438\u0438 BF &#8211; \u041d\u043e\u0432\u043e\u0435 \u0432\u0438\u0434\u0435\u043e<\/a><\/h2><\/div><\/div><div class=\"fusion-clearfix\"><\/div><\/div>\n<\/article>\n<article id=\"blog-1-post-33207\" class=\"fusion-post-grid post-33207 post type-post status-publish format-standard has-post-thumbnail hentry category-company-news-gl_ru category-latest-news-gl_ru\">\n<div class=\"fusion-post-wrapper\" style=\"background-color:rgba(255,255,255,0);border:none;\">\n\n\t\t\t<div class=\"fusion-flexslider flexslider fusion-flexslider-loading fusion-post-slideshow\" style=\"border-color:rgba(40,45,51,0);\">\n\t\t<ul class=\"slides\">\n\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<li><div  class=\"fusion-image-wrapper\" aria-haspopup=\"true\">\n\t\t\t\t<img decoding=\"async\" width=\"600\" height=\"400\" src=\"https:\/\/www.lovatoelectric.com\/wp-content\/uploads\/2022\/04\/GL_thumb.jpg\" class=\"attachment-full size-full lazyload wp-post-image\" alt=\"\" srcset=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%27http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%27%20width%3D%27600%27%20height%3D%27400%27%20viewBox%3D%270%200%20600%20400%27%3E%3Crect%20width%3D%27600%27%20height%3D%27400%27%20fill-opacity%3D%220%22%2F%3E%3C%2Fsvg%3E\" data-orig-src=\"https:\/\/www.lovatoelectric.com\/wp-content\/uploads\/2022\/04\/GL_thumb.jpg\" data-srcset=\"https:\/\/www.lovatoelectric.com\/wp-content\/uploads\/2022\/04\/GL_thumb-200x133.jpg 200w, https:\/\/www.lovatoelectric.com\/wp-content\/uploads\/2022\/04\/GL_thumb-400x267.jpg 400w, https:\/\/www.lovatoelectric.com\/wp-content\/uploads\/2022\/04\/GL_thumb.jpg 600w\" data-sizes=\"auto\" \/><div class=\"fusion-rollover\">\n\t<div class=\"fusion-rollover-content\">\n\n\t\t\t\t\n\t\t\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\n\t\t\t\t\t\t<a class=\"fusion-link-wrapper\" href=\"https:\/\/www.lovatoelectric.com\/gl_ru\/%d0%bd%d0%be%d0%b2%d0%be%d0%b5-%d0%b2%d0%b8%d0%b4%d0%b5%d0%be-%d0%be-%d0%b2%d1%8b%d0%ba%d0%bb%d1%8e%d1%87%d0%b0%d1%82%d0%b5%d0%bb%d1%8f%d1%85-%d1%80%d0%b0%d0%b7%d1%8a%d0%b5%d0%b4%d0%b8%d0%bd%d0%b8\/\" aria-label=\"\u041d\u043e\u0432\u043e\u0435 \u0432\u0438\u0434\u0435\u043e \u043e \u0432\u044b\u043a\u043b\u044e\u0447\u0430\u0442\u0435\u043b\u044f\u0445-\u0440\u0430\u0437\u044a\u0435\u0434\u0438\u043d\u0438\u0442\u0435\u043b\u044f\u0445 \u0441\u0435\u0440\u0438\u0438 GL \u0438 \u043f\u0435\u0440\u0435\u043a\u043b\u044e\u0447\u0430\u0442\u0435\u043b\u044f\u0445 \u043d\u0430\u0433\u0440\u0443\u0437\u043a\u0438\"><\/a>\n\t<\/div>\n<\/div>\n<\/div>\n<\/li>\n\t\t\t\n\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/ul>\n\t<\/div>\n\t<div class=\"fusion-post-content-wrapper\" style=\"padding:30px 0px 10px 0px;\"><div class=\"fusion-post-content post-content\"><h2 class=\"blog-shortcode-post-title entry-title\"><a href=\"https:\/\/www.lovatoelectric.com\/gl_ru\/%d0%bd%d0%be%d0%b2%d0%be%d0%b5-%d0%b2%d0%b8%d0%b4%d0%b5%d0%be-%d0%be-%d0%b2%d1%8b%d0%ba%d0%bb%d1%8e%d1%87%d0%b0%d1%82%d0%b5%d0%bb%d1%8f%d1%85-%d1%80%d0%b0%d0%b7%d1%8a%d0%b5%d0%b4%d0%b8%d0%bd%d0%b8\/\">\u041d\u043e\u0432\u043e\u0435 \u0432\u0438\u0434\u0435\u043e \u043e \u0432\u044b\u043a\u043b\u044e\u0447\u0430\u0442\u0435\u043b\u044f\u0445-\u0440\u0430\u0437\u044a\u0435\u0434\u0438\u043d\u0438\u0442\u0435\u043b\u044f\u0445 \u0441\u0435\u0440\u0438\u0438 GL \u0438 \u043f\u0435\u0440\u0435\u043a\u043b\u044e\u0447\u0430\u0442\u0435\u043b\u044f\u0445 \u043d\u0430\u0433\u0440\u0443\u0437\u043a\u0438<\/a><\/h2><\/div><\/div><div class=\"fusion-clearfix\"><\/div><\/div>\n<\/article>\n<article id=\"blog-1-post-33209\" class=\"fusion-post-grid post-33209 post type-post status-publish format-standard has-post-thumbnail hentry category-company-news-gl_ru category-latest-news-gl_ru\">\n<div class=\"fusion-post-wrapper\" style=\"background-color:rgba(255,255,255,0);border:none;\">\n\n\t\t\t<div class=\"fusion-flexslider flexslider fusion-flexslider-loading fusion-post-slideshow\" style=\"border-color:rgba(40,45,51,0);\">\n\t\t<ul class=\"slides\">\n\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<li><div  class=\"fusion-image-wrapper\" aria-haspopup=\"true\">\n\t\t\t\t<img decoding=\"async\" width=\"600\" height=\"400\" src=\"https:\/\/www.lovatoelectric.com\/wp-content\/uploads\/2022\/04\/cULus.jpg\" class=\"attachment-full size-full lazyload wp-post-image\" alt=\"\" srcset=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%27http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%27%20width%3D%27600%27%20height%3D%27400%27%20viewBox%3D%270%200%20600%20400%27%3E%3Crect%20width%3D%27600%27%20height%3D%27400%27%20fill-opacity%3D%220%22%2F%3E%3C%2Fsvg%3E\" data-orig-src=\"https:\/\/www.lovatoelectric.com\/wp-content\/uploads\/2022\/04\/cULus.jpg\" data-srcset=\"https:\/\/www.lovatoelectric.com\/wp-content\/uploads\/2022\/04\/cULus-200x133.jpg 200w, https:\/\/www.lovatoelectric.com\/wp-content\/uploads\/2022\/04\/cULus-400x267.jpg 400w, https:\/\/www.lovatoelectric.com\/wp-content\/uploads\/2022\/04\/cULus.jpg 600w\" data-sizes=\"auto\" \/><div class=\"fusion-rollover\">\n\t<div class=\"fusion-rollover-content\">\n\n\t\t\t\t\n\t\t\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\n\t\t\t\t\t\t<a class=\"fusion-link-wrapper\" href=\"https:\/\/www.lovatoelectric.com\/gl_ru\/%d0%b0%d1%81%d1%81%d0%be%d1%80%d1%82%d0%b8%d0%bc%d0%b5%d0%bd%d1%82-%d1%82%d0%b8%d1%80%d0%b8%d1%81%d1%82%d0%be%d1%80%d0%bd%d1%8b%d1%85-%d0%bc%d0%be%d0%b4%d1%83%d0%bb%d0%b5%d0%b9-%d1%81%d0%b5%d1%80\/\" aria-label=\"\u0410\u0441\u0441\u043e\u0440\u0442\u0438\u043c\u0435\u043d\u0442 \u0442\u0438\u0440\u0438\u0441\u0442\u043e\u0440\u043d\u044b\u0445 \u043c\u043e\u0434\u0443\u043b\u0435\u0439 \u0441\u0435\u0440\u0438\u0438 DCTL \u043e\u0434\u043e\u0431\u0440\u0435\u043d cULus.\"><\/a>\n\t<\/div>\n<\/div>\n<\/div>\n<\/li>\n\t\t\t\n\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/ul>\n\t<\/div>\n\t<div class=\"fusion-post-content-wrapper\" style=\"padding:30px 0px 10px 0px;\"><div class=\"fusion-post-content post-content\"><h2 class=\"blog-shortcode-post-title entry-title\"><a href=\"https:\/\/www.lovatoelectric.com\/gl_ru\/%d0%b0%d1%81%d1%81%d0%be%d1%80%d1%82%d0%b8%d0%bc%d0%b5%d0%bd%d1%82-%d1%82%d0%b8%d1%80%d0%b8%d1%81%d1%82%d0%be%d1%80%d0%bd%d1%8b%d1%85-%d0%bc%d0%be%d0%b4%d1%83%d0%bb%d0%b5%d0%b9-%d1%81%d0%b5%d1%80\/\">\u0410\u0441\u0441\u043e\u0440\u0442\u0438\u043c\u0435\u043d\u0442 \u0442\u0438\u0440\u0438\u0441\u0442\u043e\u0440\u043d\u044b\u0445 \u043c\u043e\u0434\u0443\u043b\u0435\u0439 \u0441\u0435\u0440\u0438\u0438 DCTL \u043e\u0434\u043e\u0431\u0440\u0435\u043d cULus.<\/a><\/h2><\/div><\/div><div class=\"fusion-clearfix\"><\/div><\/div>\n<\/article>\n<article id=\"blog-1-post-33158\" class=\"fusion-post-grid post-33158 post type-post status-publish format-standard has-post-thumbnail hentry category-product-news-gl_ru category-company-news-gl_ru category-highlights-gl_ru tag-lovato-2-ca_en tag-pushbuttons-ca_en\">\n<div class=\"fusion-post-wrapper\" style=\"background-color:rgba(255,255,255,0);border:none;\">\n\n\t\t\t<div class=\"fusion-flexslider flexslider fusion-flexslider-loading fusion-post-slideshow\" style=\"border-color:rgba(40,45,51,0);\">\n\t\t<ul class=\"slides\">\n\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<li><div  class=\"fusion-image-wrapper\" aria-haspopup=\"true\">\n\t\t\t\t<img decoding=\"async\" width=\"600\" height=\"400\" src=\"https:\/\/www.lovatoelectric.com\/wp-content\/uploads\/2021\/11\/s_Highlights-03-1-1.jpg\" class=\"attachment-full size-full lazyload wp-post-image\" alt=\"\" srcset=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%27http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%27%20width%3D%27600%27%20height%3D%27400%27%20viewBox%3D%270%200%20600%20400%27%3E%3Crect%20width%3D%27600%27%20height%3D%27400%27%20fill-opacity%3D%220%22%2F%3E%3C%2Fsvg%3E\" data-orig-src=\"https:\/\/www.lovatoelectric.com\/wp-content\/uploads\/2021\/11\/s_Highlights-03-1-1.jpg\" data-srcset=\"https:\/\/www.lovatoelectric.com\/wp-content\/uploads\/2021\/11\/s_Highlights-03-1-1-200x133.jpg 200w, https:\/\/www.lovatoelectric.com\/wp-content\/uploads\/2021\/11\/s_Highlights-03-1-1-400x267.jpg 400w, https:\/\/www.lovatoelectric.com\/wp-content\/uploads\/2021\/11\/s_Highlights-03-1-1.jpg 600w\" data-sizes=\"auto\" \/><div class=\"fusion-rollover\">\n\t<div class=\"fusion-rollover-content\">\n\n\t\t\t\t\n\t\t\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\n\t\t\t\t\t\t<a class=\"fusion-link-wrapper\" href=\"https:\/\/www.lovatoelectric.com\/gl_ru\/%d0%ba%d0%bd%d0%be%d0%bf%d0%ba%d0%b8-%d0%b8-%d0%bf%d0%b5%d1%80%d0%b5%d0%ba%d0%bb%d1%8e%d1%87%d0%b0%d1%82%d0%b5%d0%bb%d0%b8-%d1%81%d0%b5%d1%80%d0%b8%d0%b8-platinum-%d0%b8%d0%b4%d0%b5%d0%b0%d0%bb%d1%8c\/\" aria-label=\"\u041a\u043d\u043e\u043f\u043a\u0438 \u0438 \u043f\u0435\u0440\u0435\u043a\u043b\u044e\u0447\u0430\u0442\u0435\u043b\u0438 \u0441\u0435\u0440\u0438\u0438 Platinum, \u0438\u0434\u0435\u0430\u043b\u044c\u043d\u043e\u0435 \u0441\u043e\u0447\u0435\u0442\u0430\u043d\u0438\u0435 \u0441\u0442\u0438\u043b\u044f \u0438 \u043f\u0440\u043e\u0438\u0437\u0432\u043e\u0434\u0438\u0442\u0435\u043b\u044c\u043d\u043e\u0441\u0442\u0438\"><\/a>\n\t<\/div>\n<\/div>\n<\/div>\n<\/li>\n\t\t\t\n\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/ul>\n\t<\/div>\n\t<div class=\"fusion-post-content-wrapper\" style=\"padding:30px 0px 10px 0px;\"><div class=\"fusion-post-content post-content\"><h2 class=\"blog-shortcode-post-title entry-title\"><a href=\"https:\/\/www.lovatoelectric.com\/gl_ru\/%d0%ba%d0%bd%d0%be%d0%bf%d0%ba%d0%b8-%d0%b8-%d0%bf%d0%b5%d1%80%d0%b5%d0%ba%d0%bb%d1%8e%d1%87%d0%b0%d1%82%d0%b5%d0%bb%d0%b8-%d1%81%d0%b5%d1%80%d0%b8%d0%b8-platinum-%d0%b8%d0%b4%d0%b5%d0%b0%d0%bb%d1%8c\/\">\u041a\u043d\u043e\u043f\u043a\u0438 \u0438 \u043f\u0435\u0440\u0435\u043a\u043b\u044e\u0447\u0430\u0442\u0435\u043b\u0438 \u0441\u0435\u0440\u0438\u0438 Platinum, \u0438\u0434\u0435\u0430\u043b\u044c\u043d\u043e\u0435 \u0441\u043e\u0447\u0435\u0442\u0430\u043d\u0438\u0435 \u0441\u0442\u0438\u043b\u044f \u0438 \u043f\u0440\u043e\u0438\u0437\u0432\u043e\u0434\u0438\u0442\u0435\u043b\u044c\u043d\u043e\u0441\u0442\u0438<\/a><\/h2><\/div><\/div><div class=\"fusion-clearfix\"><\/div><\/div>\n<\/article>\n<article id=\"blog-1-post-33212\" class=\"fusion-post-grid post-33212 post type-post status-publish format-standard has-post-thumbnail hentry category-company-news-gl_ru category-latest-news-gl_ru\">\n<div class=\"fusion-post-wrapper\" style=\"background-color:rgba(255,255,255,0);border:none;\">\n\n\t\t\t<div class=\"fusion-flexslider flexslider fusion-flexslider-loading fusion-post-slideshow\" style=\"border-color:rgba(40,45,51,0);\">\n\t\t<ul class=\"slides\">\n\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<li><div  class=\"fusion-image-wrapper\" aria-haspopup=\"true\">\n\t\t\t\t<img decoding=\"async\" width=\"600\" height=\"400\" src=\"https:\/\/www.lovatoelectric.com\/wp-content\/uploads\/2021\/10\/s_Latest-03.jpg\" class=\"attachment-full size-full lazyload wp-post-image\" alt=\"\" srcset=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%27http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%27%20width%3D%27600%27%20height%3D%27400%27%20viewBox%3D%270%200%20600%20400%27%3E%3Crect%20width%3D%27600%27%20height%3D%27400%27%20fill-opacity%3D%220%22%2F%3E%3C%2Fsvg%3E\" data-orig-src=\"https:\/\/www.lovatoelectric.com\/wp-content\/uploads\/2021\/10\/s_Latest-03.jpg\" data-srcset=\"https:\/\/www.lovatoelectric.com\/wp-content\/uploads\/2021\/10\/s_Latest-03-200x133.jpg 200w, https:\/\/www.lovatoelectric.com\/wp-content\/uploads\/2021\/10\/s_Latest-03-400x267.jpg 400w, https:\/\/www.lovatoelectric.com\/wp-content\/uploads\/2021\/10\/s_Latest-03.jpg 600w\" data-sizes=\"auto\" \/><div class=\"fusion-rollover\">\n\t<div class=\"fusion-rollover-content\">\n\n\t\t\t\t\n\t\t\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\n\t\t\t\t\t\t<a class=\"fusion-link-wrapper\" href=\"https:\/\/www.lovatoelectric.com\/gl_ru\/sustainability\/\" aria-label=\"Sustainability\"><\/a>\n\t<\/div>\n<\/div>\n<\/div>\n<\/li>\n\t\t\t\n\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/ul>\n\t<\/div>\n\t<div class=\"fusion-post-content-wrapper\" style=\"padding:30px 0px 10px 0px;\"><div class=\"fusion-post-content post-content\"><h2 class=\"blog-shortcode-post-title entry-title\"><a href=\"https:\/\/www.lovatoelectric.com\/gl_ru\/sustainability\/\">Sustainability<\/a><\/h2><\/div><\/div><div class=\"fusion-clearfix\"><\/div><\/div>\n<\/article>\n<div class=\"fusion-clearfix\"><\/div><\/div><div class=\"fusion-infinite-scroll-trigger\"><\/div><div class=\"pagination infinite-scroll clearfix\" style=\"display:none;\"><span class=\"current\">1<\/span><a href=\"https:\/\/www.lovatoelectric.com\/gl_ru\/wp-json\/wp\/v2\/pages\/26204\/page\/2\/\" class=\"inactive\">2<\/a><a class=\"pagination-next\" rel=\"next\" href=\"https:\/\/www.lovatoelectric.com\/gl_ru\/wp-json\/wp\/v2\/pages\/26204\/page\/2\/\"><span class=\"page-text\">Next<\/span><span class=\"page-next\"><\/span><\/a><\/div><div class=\"fusion-clearfix\"><\/div><button class=\"fusion-load-more-button fusion-blog-button fusion-clearfix\">Load More Posts<\/button><\/div><\/div><\/div><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":16,"featured_media":0,"parent":26184,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/www.lovatoelectric.com\/gl_ru\/wp-json\/wp\/v2\/pages\/26204"}],"collection":[{"href":"https:\/\/www.lovatoelectric.com\/gl_ru\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.lovatoelectric.com\/gl_ru\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.lovatoelectric.com\/gl_ru\/wp-json\/wp\/v2\/users\/16"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lovatoelectric.com\/gl_ru\/wp-json\/wp\/v2\/comments?post=26204"}],"version-history":[{"count":0,"href":"https:\/\/www.lovatoelectric.com\/gl_ru\/wp-json\/wp\/v2\/pages\/26204\/revisions"}],"up":[{"embeddable":true,"href":"https:\/\/www.lovatoelectric.com\/gl_ru\/wp-json\/wp\/v2\/pages\/26184"}],"wp:attachment":[{"href":"https:\/\/www.lovatoelectric.com\/gl_ru\/wp-json\/wp\/v2\/media?parent=26204"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}